{"id":5083,"date":"2018-02-03T08:55:12","date_gmt":"2018-02-03T08:55:12","guid":{"rendered":"https:\/\/www.calcetinespersonalizados.es\/producto\/mitjons-tecnics-1503\/"},"modified":"2020-07-25T06:16:38","modified_gmt":"2020-07-25T06:16:38","slug":"mitjo-de-coto-tecnic-1503","status":"publish","type":"product","link":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/","title":{"rendered":"Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503"},"content":{"rendered":"<p>Mitj\u00f3 esportiu amb tovallola a la planta del peu i goma compressiva en canya per a una major subjecci\u00f3 c\u00f2modes i adequats per a qualsevol tipus d&#8217;esport.<br \/>\nFabricaci\u00f3 i disseny propis.<br \/>\nCompra les teves mitjons en l\u00ednia i rep el lliurament en 48 hores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mitj\u00f3 esportiu amb tovallola a la planta del peu i goma compressiva en canya per a una major subjecci\u00f3 c\u00f2modes i adequats per a qualsevol tipus d&#8217;esport.<br \/>\nFabricaci\u00f3 i disseny propis.<br \/>\nCompra les teves mitjons en l\u00ednia i rep el lliurament en 48 hores.<\/p>\n<p><strong>Composici\u00f3:<br \/>\n<\/strong>80% COT\u00d3<br \/>\n17% POLIAMIDA<br \/>\n3% ELAST\u00c0<\/p>\n<p><span style=\"color: #ff6600;\"><strong>Talles M 36-40<\/strong><\/span><\/p>\n","protected":false},"featured_media":4446,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[323,325],"product_tag":[],"class_list":{"0":"post-5083","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-esportius","7":"product_cat-tecnics","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503 - Calcelinea S.L. - Fabricants de Mitjons<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503 - Calcelinea S.L. - Fabricants de Mitjons\" \/>\n<meta property=\"og:description\" content=\"Mitj\u00f3 esportiu amb tovallola a la planta del peu i goma compressiva en canya per a una major subjecci\u00f3 c\u00f2modes i adequats per a qualsevol tipus d&#039;esport. Fabricaci\u00f3 i disseny propis. Compra les teves mitjons en l\u00ednia i rep el lliurament en 48 hores.  Composici\u00f3: 80% COT\u00d3 17% POLIAMIDA 3% ELAST\u00c0  Talles M 36-40\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/\" \/>\n<meta property=\"og:site_name\" content=\"Calcelinea S.L. - Fabricants de Mitjons\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doremi.doremicalcelinea\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-25T06:16:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.calcetinespersonalizados.es\/wp-content\/uploads\/2018\/02\/1503-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/producte\\\/mitjo-de-coto-tecnic-1503\\\/\",\"url\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/producte\\\/mitjo-de-coto-tecnic-1503\\\/\",\"name\":\"Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503 - Calcelinea S.L. - Fabricants de Mitjons\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/producte\\\/mitjo-de-coto-tecnic-1503\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/producte\\\/mitjo-de-coto-tecnic-1503\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1503-1.jpg\",\"datePublished\":\"2018-02-03T08:55:12+00:00\",\"dateModified\":\"2020-07-25T06:16:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/producte\\\/mitjo-de-coto-tecnic-1503\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/producte\\\/mitjo-de-coto-tecnic-1503\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/producte\\\/mitjo-de-coto-tecnic-1503\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1503-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/1503-1.jpg\",\"width\":750,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/producte\\\/mitjo-de-coto-tecnic-1503\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/botiga\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/\",\"name\":\"Calcelinea S.L. - Fabricants de Mitjons\",\"description\":\"Fabricants de Mitjons\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/#organization\"},\"alternateName\":\"Calcelinea SL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/#organization\",\"name\":\"Fabricantes de calcetines personalizados - Calcelinea S.L.\",\"url\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo@x2.png\",\"contentUrl\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/logo@x2.png\",\"width\":264,\"height\":72,\"caption\":\"Fabricantes de calcetines personalizados - Calcelinea S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.calcetinespersonalizados.es\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doremi.doremicalcelinea\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503 - Calcelinea S.L. - Fabricants de Mitjons","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/","og_locale":"ca_ES","og_type":"article","og_title":"Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503 - Calcelinea S.L. - Fabricants de Mitjons","og_description":"Mitj\u00f3 esportiu amb tovallola a la planta del peu i goma compressiva en canya per a una major subjecci\u00f3 c\u00f2modes i adequats per a qualsevol tipus d'esport. Fabricaci\u00f3 i disseny propis. Compra les teves mitjons en l\u00ednia i rep el lliurament en 48 hores.  Composici\u00f3: 80% COT\u00d3 17% POLIAMIDA 3% ELAST\u00c0  Talles M 36-40","og_url":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/","og_site_name":"Calcelinea S.L. - Fabricants de Mitjons","article_publisher":"https:\/\/www.facebook.com\/doremi.doremicalcelinea","article_modified_time":"2020-07-25T06:16:38+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/www.calcetinespersonalizados.es\/wp-content\/uploads\/2018\/02\/1503-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/","url":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/","name":"Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503 - Calcelinea S.L. - Fabricants de Mitjons","isPartOf":{"@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/#primaryimage"},"image":{"@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/#primaryimage"},"thumbnailUrl":"https:\/\/www.calcetinespersonalizados.es\/wp-content\/uploads\/2018\/02\/1503-1.jpg","datePublished":"2018-02-03T08:55:12+00:00","dateModified":"2020-07-25T06:16:38+00:00","breadcrumb":{"@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/#primaryimage","url":"https:\/\/www.calcetinespersonalizados.es\/wp-content\/uploads\/2018\/02\/1503-1.jpg","contentUrl":"https:\/\/www.calcetinespersonalizados.es\/wp-content\/uploads\/2018\/02\/1503-1.jpg","width":750,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/producte\/mitjo-de-coto-tecnic-1503\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.calcetinespersonalizados.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/www.calcetinespersonalizados.es\/ca\/botiga\/"},{"@type":"ListItem","position":3,"name":"Mitj\u00f3 de Cot\u00f3 T\u00e8cnic 1503"}]},{"@type":"WebSite","@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/#website","url":"https:\/\/www.calcetinespersonalizados.es\/ca\/","name":"Calcelinea S.L. - Fabricants de Mitjons","description":"Fabricants de Mitjons","publisher":{"@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/#organization"},"alternateName":"Calcelinea SL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.calcetinespersonalizados.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/#organization","name":"Fabricantes de calcetines personalizados - Calcelinea S.L.","url":"https:\/\/www.calcetinespersonalizados.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.calcetinespersonalizados.es\/wp-content\/uploads\/2017\/12\/logo@x2.png","contentUrl":"https:\/\/www.calcetinespersonalizados.es\/wp-content\/uploads\/2017\/12\/logo@x2.png","width":264,"height":72,"caption":"Fabricantes de calcetines personalizados - Calcelinea S.L."},"image":{"@id":"https:\/\/www.calcetinespersonalizados.es\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doremi.doremicalcelinea"]}]}},"_links":{"self":[{"href":"https:\/\/www.calcetinespersonalizados.es\/ca\/wp-json\/wp\/v2\/product\/5083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.calcetinespersonalizados.es\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.calcetinespersonalizados.es\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.calcetinespersonalizados.es\/ca\/wp-json\/wp\/v2\/media\/4446"}],"wp:attachment":[{"href":"https:\/\/www.calcetinespersonalizados.es\/ca\/wp-json\/wp\/v2\/media?parent=5083"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.calcetinespersonalizados.es\/ca\/wp-json\/wp\/v2\/product_brand?post=5083"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.calcetinespersonalizados.es\/ca\/wp-json\/wp\/v2\/product_cat?post=5083"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.calcetinespersonalizados.es\/ca\/wp-json\/wp\/v2\/product_tag?post=5083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}